{"id":15811,"date":"2023-12-28T08:12:53","date_gmt":"2023-12-28T08:12:53","guid":{"rendered":"https:\/\/besonix.ch\/?post_type=product&#038;p=15811"},"modified":"2026-07-07T01:37:29","modified_gmt":"2026-07-07T01:37:29","slug":"tp-b877-batterie-3d-spiegel-magnet-led-tanzflache","status":"publish","type":"product","link":"https:\/\/besonix.ch\/fr\/product\/tp-b877-batterie-3d-spiegel-magnet-led-tanzflache\/","title":{"rendered":"TP-B877 Batterie Miroir 3D Magn\u00e9tique Piste de Danse LED"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"15811\" class=\"elementor elementor-15811\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dadb395 e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"4dadb395\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5932a1 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"3f5932a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous souhaitez que votre \u00e9v\u00e9nement soit unique ? Vous souhaitez que votre \u00e9v\u00e9nement soit incomparable ? \u00cates-vous toujours confus quant \u00e0 l&#039;installation de pistes de danse LED avec des c\u00e2bles\u00a0? La piste de danse magn\u00e9tique \u00e0 LED avec miroir 3D sans fil TP-B877 r\u00e9pond \u00e0 tous vos besoins et r\u00e9sout les probl\u00e8mes d&#039;installation ennuyeux. Notre piste de danse LED est con\u00e7ue pour remplacer vos sols en bois ou en b\u00e9ton traditionnels, ennuyeux et peu esth\u00e9tiques. Il est parfait pour votre f\u00eate, \u00e9v\u00e9nement ou mariage et peut \u00eatre utilis\u00e9 dans n\u2019importe quel d\u00e9cor int\u00e9rieur. Avec un spectacle de lumi\u00e8re LED qui \u00e9blouira vos invit\u00e9s, c&#039;est le moyen id\u00e9al pour rendre votre prochain \u00e9v\u00e9nement inoubliable !<br \/>Nous offrons le meilleur prix, qualit\u00e9 et service. Si vous \u00eates dans le secteur de l&#039;\u00e9v\u00e9nementiel ou souhaitez vous lancer dans le secteur, c&#039;est le bon choix pour vous. Commandez la piste de danse LED d\u00e8s aujourd&#039;hui - vous ne le regretterez pas !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-744689b e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"744689b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-262d38c elementor-widget elementor-widget-heading\" data-id=\"262d38c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages du produit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06c017d e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"06c017d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a3a7f6 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"1a3a7f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><strong>Installation facile et rapide :<\/strong> <\/span>La piste de danse est verrouillable magn\u00e9tiquement et vous offre une merveilleuse exp\u00e9rience d&#039;installation facile. Allumez l&#039;interrupteur et vous pourrez profiter d&#039;une installation en quelques secondes. L&#039;ensemble de l&#039;installation peut \u00eatre r\u00e9alis\u00e9 en seulement 8 minutes\u00a0!<\/p><p><strong><span style=\"text-decoration: underline;\">Diff\u00e9rentes m\u00e9thodes fiscales :<\/span><\/strong> Il prend en charge diverses m\u00e9thodes de contr\u00f4le, notamment la t\u00e9l\u00e9commande, le contr\u00f4le DMX et le contr\u00f4le par ordinateur. Vous pouvez librement s\u00e9lectionner des couleurs, motifs, styles et autres effets alternatifs avec la t\u00e9l\u00e9commande incluse.<\/p><p><span style=\"text-decoration: underline;\"><strong>Divers effets :<\/strong><\/span> Il peut pr\u00e9senter divers effets changeants tels qu&#039;un effet RVB mixte, une couleur compl\u00e8te, un effet \u00e9toile, un effet 3D, etc. Donnez vie \u00e0 votre \u00e9v\u00e9nement avec des effets impressionnants et sp\u00e9ciaux\u00a0!<\/p><p><span style=\"text-decoration: underline;\"><strong>Longue dur\u00e9e de vie\u00a0:<\/strong><\/span> La dur\u00e9e de vie de la LED est de 50 000 heures. Il n\u2019y aura donc aucune situation embarrassante de panne de courant soudaine pendant l\u2019utilisation.<\/p><p><span style=\"text-decoration: underline;\"><strong>\u00c9conomie d&#039;\u00e9nergie:<\/strong> <\/span>La puissance du panneau est de 20 watts, ce qui permet d&#039;\u00e9conomiser davantage d&#039;\u00e9nergie.<\/p><p><strong><span style=\"text-decoration: underline;\">Batterie int\u00e9gr\u00e9e :<\/span><\/strong> Il a \u00e9t\u00e9 construit avec la technologie am\u00e9lior\u00e9e dans laquelle la batterie int\u00e9gr\u00e9e y \u00e9tait install\u00e9e. La batterie int\u00e9gr\u00e9e rend son utilisation beaucoup plus facile et pratique. Il ne faut que quatre heures de charge pour obtenir plus de 10 heures d\u2019autonomie.<\/p><p><span style=\"text-decoration: underline;\"><strong>Performances stables\u00a0:<\/strong><\/span> Garantit des performances stables m\u00eame en cas d&#039;utilisation \u00e0 long terme, une longue dur\u00e9e de vie, un signal et une alimentation stables et une utilisation s\u00fbre.<\/p><p><span style=\"text-decoration: underline;\"><strong>Capacit\u00e9 de charge sup\u00e9rieure\u00a0:<\/strong><\/span> La capacit\u00e9 de charge peut \u00eatre maintenue \u00e0 un niveau \u00e9lev\u00e9. Gr\u00e2ce \u00e0 une technologie avanc\u00e9e, la capacit\u00e9 de charge de chaque panneau est sup\u00e9rieure \u00e0 500-600 kg. Ainsi, supporter le poids d&#039;une voiture ou d&#039;une foule n&#039;est pas un probl\u00e8me pour la piste de danse LED \u00e0 aimant miroir 3D \u00e0 batterie TP-B877.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-16397 size-full\" src=\"https:\/\/besonix.ch\/wp-content\/uploads\/2024\/01\/20230307162746321.jpg\" alt=\"\" width=\"900\" height=\"1200\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-025e3ce e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"025e3ce\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0dbc653 elementor-widget elementor-widget-heading\" data-id=\"0dbc653\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">sp\u00e9cification<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46c43df e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"46c43df\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3dd5bb color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"c3dd5bb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\"><tbody><tr class=\"firstRow\" align=\"center\"><td>Nom de production<\/td><td>Piste de danse magn\u00e9tique avec miroir 3D \u00e0 batterie<\/td><\/tr><tr align=\"center\"><td>Mod\u00e8le<\/td><td>TP-B877<\/td><\/tr><tr align=\"center\"><td>Taille<\/td><td>50cmx50cmx7cm<\/td><\/tr><tr align=\"center\"><td>Poids<\/td><td>8,5 kg<\/td><\/tr><tr align=\"center\"><td>Mat\u00e9riau de surface<\/td><td>Verre tremp\u00e9 de 10 mm d&#039;\u00e9paisseur<\/td><\/tr><tr align=\"center\"><td>Mat\u00e9riau du fond<\/td><td>Bo\u00eetier en plastique, ABS<\/td><\/tr><tr align=\"center\"><td>Imperm\u00e9able<\/td><td>IP53<\/td><\/tr><tr align=\"center\"><td>Source de lumi\u00e8re<\/td><td>SMD5050, RVB, 64 pi\u00e8ces<\/td><\/tr><tr align=\"center\"><td>Performances du panneau<\/td><td>20W<\/td><\/tr><tr align=\"center\"><td>Tension du panneau<\/td><td>24V<\/td><\/tr><tr align=\"center\"><td>Courant \u00e9lectrique du panneau<\/td><td>0,83A<\/td><\/tr><tr align=\"center\"><td>dur\u00e9e de vie<\/td><td>50 000 heures<\/td><\/tr><tr align=\"center\"><td>Temp\u00e9rature de fonctionnement<\/td><td>-50 \u2103- 60 \u2103<\/td><\/tr><tr align=\"center\"><td>Assembl\u00e9e<\/td><td>Connexion magn\u00e9tique<\/td><\/tr><tr align=\"center\"><td>Caract\u00e9ristiques<\/td><td>Couleurs unies, m\u00e9lange d&#039;effets RVB, effet \u00e9toile<\/td><\/tr><tr align=\"center\"><td>Temps de chargement<\/td><td>4 heures<\/td><\/tr><tr align=\"center\"><td>Vie de la batterie<\/td><td>10+ heures<\/td><\/tr><tr align=\"center\"><td>pilotage<\/td><td>T\u00e9l\u00e9commande, ordinateur, DMX, contr\u00f4leur<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5a0258 e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"a5a0258\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c502805 elementor-widget elementor-widget-heading\" data-id=\"c502805\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Description du produit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a793043 e-flex e-con-boxed wd-section-disabled e-con e-parent\" data-id=\"a793043\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-713c3cb wd-accordion-theme-style elementor-widget elementor-widget-accordion\" data-id=\"713c3cb\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1181\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1181\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Mat\u00e9riau r\u00e9sistant<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1181\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1181\"><p><span style=\"text-decoration: underline;\"><strong>Mat\u00e9riau de surface\u00a0:<\/strong><\/span><br \/>La surface de la piste de danse est enti\u00e8rement recouverte de verre tremp\u00e9 r\u00e9sistant de 10 mm, pouvant supporter de 500 \u00e0 600 kg. Le verre tremp\u00e9 a une haute r\u00e9sistance \u00e0 la traction et est extr\u00eamement durable. Il p\u00e8se 8,5 kilogrammes et mesure 7 cm d&#039;\u00e9paisseur.<\/p><p><strong><span style=\"text-decoration: underline;\">Mat\u00e9riau du fond :<\/span><\/strong><br \/>Il s&#039;agit d&#039;un bo\u00eetier en plastique ABS, plus durable et adapt\u00e9 \u00e0 une utilisation \u00e0 long terme.<\/p><p><span style=\"text-decoration: underline;\"><strong>Haute r\u00e9silience :<\/strong><\/span><br \/>Il est suffisamment solide pour supporter environ cinq \u00e0 six cents kilogrammes de charge. En raison de sa capacit\u00e9 de charge sup\u00e9rieure, il ne se fissurera pas facilement, m\u00eame avec un grand nombre de personnes dansant.<\/p><p><img decoding=\"async\" class=\"alignnone wp-image-16399 size-full\" src=\"https:\/\/besonix.ch\/wp-content\/uploads\/2024\/01\/20230307162751475-1.jpg\" alt=\"\" width=\"900\" height=\"732\" \/><\/p><p><img decoding=\"async\" class=\"alignnone size-full wp-image-16400\" src=\"https:\/\/besonix.ch\/wp-content\/uploads\/2024\/01\/20230307162743203.jpg\" alt=\"\" width=\"900\" height=\"918\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1182\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1182\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Conception professionnelle<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1182\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1182\"><p><span style=\"text-decoration: underline;\"><strong>Personnalisation personnalis\u00e9e\u00a0:<\/strong><\/span><br \/>La taille du panneau est de 50 cm x 50 cm x 7 cm. Nous pouvons proposer une personnalisation selon vos besoins.<\/p><p><span style=\"text-decoration: underline;\"><strong>Conception des bords\u00a0:<\/strong><\/span><br \/>Il est \u00e9quip\u00e9 d&#039;un design de bord nouvellement am\u00e9lior\u00e9 pour mieux \u00e9viter les glissements et les chutes.<\/p><p><span style=\"text-decoration: underline;\"><strong>Haute r\u00e9silience :<\/strong><\/span><br \/>Il est suffisamment solide pour supporter environ cinq \u00e0 six cents kilogrammes de charge. En raison de sa capacit\u00e9 de charge sup\u00e9rieure, il ne se fissurera pas facilement, m\u00eame avec un grand nombre de personnes dansant.<\/p><p>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16401\" src=\"https:\/\/besonix.ch\/wp-content\/uploads\/2024\/01\/20230307161401851.jpg\" alt=\"\" width=\"900\" height=\"1198\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1183\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1183\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Installation rapide et pratique<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1183\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1183\"><p>Les panneaux de la piste de danse LED TP-B877 Battery 3D Mirror Magnet sont verrouillables magn\u00e9tiquement, ce qui offre la possibilit\u00e9 d&#039;obtenir le r\u00e9sultat d&#039;une installation en une seconde. Les performances sup\u00e9rieures du panneau et son syst\u00e8me magn\u00e9tique avanc\u00e9 permettent une installation, un retrait et un transport rapides et faciles.<\/p><p><span style=\"text-decoration: underline;\"><strong>\u00c9conomisez du temps et des co\u00fbts de main d&#039;\u0153uvre\u00a0:<\/strong><\/span><br \/>Ce syst\u00e8me d&#039;installation sans fil ou sans fil permet d&#039;\u00e9conomiser beaucoup de temps et de co\u00fbts de main d&#039;\u0153uvre. Il est facile \u00e0 installer en quelques secondes seulement. Il n\u2019est pas n\u00e9cessaire d\u2019embaucher beaucoup de personnes pour le construire. De plus, cela \u00e9vite les probl\u00e8mes de c\u00e2blage compliqu\u00e9. Tout ce que vous avez \u00e0 faire est d&#039;allumer l&#039;interrupteur, de les disposer soigneusement et de les connecter ensemble.<\/p><p><span style=\"text-decoration: underline;\"><strong>Mode d&#039;emploi:<\/strong><\/span><br \/>Un manuel d&#039;instructions pr\u00e9cis et une vid\u00e9o sont fournis pour aider les clients \u00e0 terminer avec succ\u00e8s les t\u00e2ches d&#039;installation.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1184\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1184\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Excellent syst\u00e8me de t\u00e9l\u00e9commande<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1184\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1184\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16402\" src=\"https:\/\/besonix.ch\/wp-content\/uploads\/2024\/01\/20230307161405835.jpg\" alt=\"\" width=\"900\" height=\"1198\" \/><\/p><p><span style=\"text-decoration: underline;\"><strong>Plusieurs m\u00e9thodes de syst\u00e8me de contr\u00f4le\u00a0:<\/strong><\/span><br \/>La piste de danse dispose de trois types de modes de contr\u00f4le diff\u00e9rents, dont la t\u00e9l\u00e9commande, le contr\u00f4le DMX et le contr\u00f4le par ordinateur.<\/p><p><strong><span style=\"text-decoration: underline;\">Les fonctions du syst\u00e8me fiscal :<\/span><\/strong><br \/>Ces divers syst\u00e8mes de contr\u00f4le rendent la modification des motifs et des couleurs beaucoup plus pratique et facile. La t\u00e9l\u00e9commande incluse permet au client de choisir la couleur, le motif et bien plus encore, et permet au client d&#039;\u00e9changer librement les effets et les modes en fonction du programme d&#039;activit\u00e9. Le syst\u00e8me de t\u00e9l\u00e9commande permet aux clients de modifier les effets et les modes \u00e0 volont\u00e9 et de pr\u00e9senter des performances color\u00e9es et \u00e9tonnantes pour les activit\u00e9s.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1185\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1185\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Plusieurs couleurs et effets<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1185\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1185\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16403\" src=\"https:\/\/besonix.ch\/wp-content\/uploads\/2024\/01\/TP-B87703.jpg.jpg\" alt=\"\" width=\"900\" height=\"1066\" \/><\/p><p><span style=\"text-decoration: underline;\"><strong>La couleur et la quantit\u00e9 de lumi\u00e8re : <\/strong><\/span>Il utilise le SMD5050 de haute qualit\u00e9 comme source de lumi\u00e8re et contient 64 perles de lampe, ce qui peut garantir la luminosit\u00e9 de l&#039;effet.<br \/><strong><span style=\"text-decoration: underline;\"><br \/>Une large gamme de couleurs et de nombreux effets : <\/span><\/strong>Les panneaux peuvent afficher une vari\u00e9t\u00e9 d&#039;effets tels que la couleur, l&#039;effet \u00e9toile, le m\u00e9lange d&#039;effet RVB et l&#039;effet infini 3D. Le syst\u00e8me de t\u00e9l\u00e9commande peut facilement contr\u00f4ler l&#039;\u00e9tat de l&#039;affichage de l&#039;effet, et la transformation de l&#039;effet, la luminosit\u00e9, la vitesse, la couleur et le d\u00e9grad\u00e9 peuvent \u00eatre facilement utilis\u00e9s.<br \/><span style=\"text-decoration: underline;\"><strong><br \/>Effet \u00e9toile : <\/strong><\/span>Sc\u00e8ne magique sp\u00e9ciale, l&#039;\u00e9quipe R&amp;D a d\u00e9velopp\u00e9 ce nouveau mod\u00e8le sp\u00e9cial avec 30 types d&#039;effets d&#039;\u00e9toiles, qui peuvent non seulement modifier la vitesse, la couleur et la luminosit\u00e9, mais \u00e9galement fournir diff\u00e9rents styles. Pour le rendre adapt\u00e9 \u00e0 des \u00e9v\u00e9nements tels que des f\u00eates et des spectacles divers.<\/p><p><strong><span style=\"text-decoration: underline;\">Pleine couleur\u00a0:<\/span><\/strong> Il peut afficher 7 couleurs dont le jaune, le rouge, le vert, le bleu, le violet, le rose et le blanc. Non seulement il peut changer de couleur et ajuster la luminosit\u00e9, mais \u00e9galement montrer un effet stroboscopique. Cet effet color\u00e9 classique convient aux d\u00e9fil\u00e9s de mode et aux soir\u00e9es dansantes.<br \/><span style=\"text-decoration: underline;\"><strong><br \/>M\u00e9langer l&#039;effet RVB\u00a0: <\/strong><\/span>L&#039;effet Mix RGB est un effet cool et dynamique. Il peut pr\u00e9senter un effet de sc\u00e8ne dynamique et cr\u00e9er une atmosph\u00e8re unique. L&#039;effet Mix RGB convient aux \u00e9v\u00e9nements tels que les repr\u00e9sentations sc\u00e9niques et les spectacles divers.<\/p><p><span style=\"text-decoration: underline;\"><strong>Effet infini 3D\u00a0: <\/strong><\/span>Il peut pr\u00e9senter le merveilleux effet infini 3D. Cet effet est tr\u00e8s populaire. La conception 3D unique offre des effets de sc\u00e8ne haut de gamme et uniques, montrant une exp\u00e9rience visuelle moderne et \u00e0 la mode. Gr\u00e2ce \u00e0 ces caract\u00e9ristiques, il peut \u00eatre largement utilis\u00e9 dans de nombreux \u00e9v\u00e9nements, tels que les salons automobiles, les bars, les d\u00e9corations d&#039;expositions, les anniversaires, etc.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Strapazierf\\u00e4higes Material\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"text-decoration: underline;\\\"><strong>Material der Oberfl\\u00e4che:<\\\/strong><\\\/span><br \\\/>Die Oberfl\\u00e4che der Tanzfl\\u00e4che ist vollst\\u00e4ndig mit starkem 10 mm starkem geh\\u00e4rtetem Glas bedeckt, das 500 kg bis 600 kg tragen kann. Das geh\\u00e4rtete Glas hat eine hohe Zugfestigkeit und ist \\u00e4u\\u00dferst langlebig. Es hat ein Gewicht von 8,5 Kilogramm und eine Dicke von 7 cm.<\\\/p><p><strong><span style=\\\"text-decoration: underline;\\\">Material der Unterseite:<\\\/span><\\\/strong><br \\\/>Es handelt sich um ein ABS-Kunststoffgeh\\u00e4use, das langlebiger und f\\u00fcr den Langzeitgebrauch geeignet ist.<\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Hohe Belastbarkeit:<\\\/strong><\\\/span><br \\\/>Es ist stark genug, um etwa f\\u00fcnfhundert bis sechshundert Kilogramm der Ladung zu tragen. Aufgrund seiner \\u00fcberlegenen Tragf\\u00e4higkeit wird es selbst bei einer gro\\u00dfen Anzahl tanzender Menschen nicht so leicht zu Rissen kommen.<\\\/p><p><img class=\\\"alignnone wp-image-16399 size-full\\\" src=\\\"https:\\\/\\\/besonix.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/20230307162751475-1.jpg\\\" alt=\\\"\\\" width=\\\"900\\\" height=\\\"732\\\" \\\/><\\\/p><p><img class=\\\"alignnone size-full wp-image-16400\\\" src=\\\"https:\\\/\\\/besonix.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/20230307162743203.jpg\\\" alt=\\\"\\\" width=\\\"900\\\" height=\\\"918\\\" \\\/><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Professionelles Design\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"text-decoration: underline;\\\"><strong>Personalisierte Anpassung:<\\\/strong><\\\/span><br \\\/>Die Gr\\u00f6\\u00dfe des Panels betr\\u00e4gt 50cmx50cmx7cm. Wir k\\u00f6nnen eine Anpassung entsprechend Ihren Bed\\u00fcrfnissen anbieten.<\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Kantendesign:<\\\/strong><\\\/span><br \\\/>Es ist mit einem neu verbesserten Kantendesign ausgestattet, um ein Verrutschen und Herunterfallen besser zu verhindern.<\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Hohe Belastbarkeit:<\\\/strong><\\\/span><br \\\/>Es ist stark genug, um etwa f\\u00fcnfhundert bis sechshundert Kilogramm der Ladung zu tragen. Aufgrund seiner \\u00fcberlegenen Tragf\\u00e4higkeit wird es selbst bei einer gro\\u00dfen Anzahl tanzender Menschen nicht so leicht zu Rissen kommen.<\\\/p><p>\\u00a0<\\\/p><p><img class=\\\"alignnone size-full wp-image-16401\\\" src=\\\"https:\\\/\\\/besonix.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/20230307161401851.jpg\\\" alt=\\\"\\\" width=\\\"900\\\" height=\\\"1198\\\" \\\/><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Schnelle und bequeme Installation\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Die Paneele des TP-B877 Battery 3D Mirror Magnet LED-Tanzbodens sind magnetisch verriegelbar, was die M\\u00f6glichkeit bietet, das Ergebnis einer Ein-Sekunden-Installation zu erzielen. Die \\u00fcberragende Leistung des Panels und das fortschrittliche Magnet-System erm\\u00f6glichen eine schnelle und einfache Installation, Entfernung und Transport.<\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Zeit und Arbeitskosten sparen:<\\\/strong><\\\/span><br \\\/>Dieses kabellose oder kabellose Installationssystem spart erheblich Zeit und Arbeitskosten. Es ist einfach in nur wenigen Sekunden zu installieren. Es ist nicht notwendig, eine Menge Leute f\\u00fcr den Aufbau einzustellen. Dar\\u00fcber hinaus vermeidet es die M\\u00fche der komplizierten Verdrahtung. Alles, was Sie tun m\\u00fcssen, ist den Schalter einzuschalten, sie ordentlich anzuordnen und miteinander zu verbinden.<\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Bedienungsanleitung:<\\\/strong><\\\/span><br \\\/>Eine genaue Bedienungsanleitung und ein Video werden bereitgestellt, um Kunden bei der erfolgreichen Durchf\\u00fchrung von Installationsaufgaben zu unterst\\u00fctzen.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Ausgezeichnetes Fernbedienungssystem\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><img class=\\\"alignnone size-full wp-image-16402\\\" src=\\\"https:\\\/\\\/besonix.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/20230307161405835.jpg\\\" alt=\\\"\\\" width=\\\"900\\\" height=\\\"1198\\\" \\\/><\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Mehrere Steuersystemmethoden:<\\\/strong><\\\/span><br \\\/>Der Tanzboden verf\\u00fcgt \\u00fcber drei verschiedene Arten von Steuermodi, darunter die Fernbedienung, die DMX-Steuerung und die Computersteuerung.<\\\/p><p><strong><span style=\\\"text-decoration: underline;\\\">Die Funktionen des Steuersystems:<\\\/span><\\\/strong><br \\\/>Diese vielf\\u00e4ltigen Steuersysteme machen es viel bequemer und einfacher, die Muster und Farben zu \\u00e4ndern. Der mitgelieferte Fernbedienung erm\\u00f6glicht es dem Kunden, die Farbe, das Muster und mehr nach Belieben auszuw\\u00e4hlen, und erm\\u00f6glicht es dem Kunden, Effekte und Modi frei gem\\u00e4\\u00df dem Aktivit\\u00e4tszeitplan auszutauschen. Das Fernbedienungssystem erm\\u00f6glicht es Kunden, Effekte und Modi nach Belieben zu \\u00e4ndern und bunte und erstaunliche Darbietungen f\\u00fcr Aktivit\\u00e4ten zu pr\\u00e4sentieren.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Mehrere Farben und Effekte\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><img class=\\\"alignnone size-full wp-image-16403\\\" src=\\\"https:\\\/\\\/besonix.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/TP-B87703.jpg.jpg\\\" alt=\\\"\\\" width=\\\"900\\\" height=\\\"1066\\\" \\\/><\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>Die Farbe und Menge des Lichts: <\\\/strong><\\\/span>Es verwendet die hochwertige SMD5050 als Lichtquelle und enth\\u00e4lt 64 Lampenperlen, die die Helligkeit des Effekts garantieren k\\u00f6nnen.<br \\\/><strong><span style=\\\"text-decoration: underline;\\\"><br \\\/>Eine breite Farbpalette und zahlreiche Effekte: <\\\/span><\\\/strong>Die Paneele k\\u00f6nnen eine Vielzahl von Effekten anzeigen, wie Vollfarbe, Sterneneffekt, Mix-RGB-Effekt und 3D-Infinity-Effekt. Das Fernbedienungssystem kann den Zustand der Effektdarstellung einfach steuern, und die Effekttransformation, Helligkeit, Geschwindigkeit, Farbe und der Farbverlauf k\\u00f6nnen leicht bedient werden.<br \\\/><span style=\\\"text-decoration: underline;\\\"><strong><br \\\/>Sterneneffekt: <\\\/strong><\\\/span>Besondere magische Szene, das F&amp;E-Team hat dieses neue spezielle Modell mit 30 Arten von Sterneneffekten entwickelt, die nicht nur die Geschwindigkeit, Farbe und Helligkeit \\u00e4ndern k\\u00f6nnen, sondern auch verschiedene Stile bieten. Um es f\\u00fcr Veranstaltungen wie Partys und verschiedene Shows geeignet zu machen.<\\\/p><p><strong><span style=\\\"text-decoration: underline;\\\">Vollfarbe:<\\\/span><\\\/strong> Es kann 7 Farben anzeigen, einschlie\\u00dflich Gelb, Rot, Gr\\u00fcn, Blau, Lila, Rosa und Wei\\u00df. Es kann nicht nur die Farben \\u00e4ndern und die Helligkeit anpassen, sondern auch einen stroboskopischen Effekt zeigen. Dieser klassische Vollfarbeffekt eignet sich f\\u00fcr Modenschauen und Tanzpartys.<br \\\/><span style=\\\"text-decoration: underline;\\\"><strong><br \\\/>Mix-RGB-Effekt: <\\\/strong><\\\/span>Der Mix-RGB-Effekt ist ein cooler und dynamischer Effekt. Er kann einen dynamischen B\\u00fchneneffekt pr\\u00e4sentieren und eine einzigartige Atmosph\\u00e4re schaffen. Der Mix-RGB-Effekt eignet sich f\\u00fcr Veranstaltungen wie B\\u00fchnenperformances und verschiedene Shows.<\\\/p><p><span style=\\\"text-decoration: underline;\\\"><strong>3D-Infinity-Effekt: <\\\/strong><\\\/span>Er kann den wunderbaren 3D-Infinity-Effekt pr\\u00e4sentieren. Dieser Effekt ist sehr beliebt. Das einzigartige 3D-Design bietet High-End- und einzigartige B\\u00fchneneffekte und zeigt eine moderne und modische visuelle Erfahrung. Mit diesen Merkmalen kann er weit verbreitet in vielen Veranstaltungen eingesetzt werden, wie z.B. Autoschauen, Bars, Ausstellungsd ekorationen, Geburtstagsveranstaltungen usw.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Installation rapide<\/li>\n<li>Syst\u00e8me magn\u00e9tique<\/li>\n<li>Divers effets sympas<\/li>\n<li>Plusieurs m\u00e9thodes de contr\u00f4le<\/li>\n<li>Grande capacit\u00e9 de charge<\/li>\n<\/ul>","protected":false},"featured_media":16363,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[72],"product_tag":[],"class_list":{"0":"post-15811","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-batteriemagnet-led-tanzflache","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/product\/15811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/comments?post=15811"}],"version-history":[{"count":32,"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/product\/15811\/revisions"}],"predecessor-version":[{"id":16637,"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/product\/15811\/revisions\/16637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/media\/16363"}],"wp:attachment":[{"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/media?parent=15811"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=15811"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/besonix.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=15811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}